{"id":1895,"date":"2024-10-01T09:01:59","date_gmt":"2024-10-01T09:01:59","guid":{"rendered":"https:\/\/cilfa.org.ar\/wp1\/?p=1895"},"modified":"2024-10-01T09:02:35","modified_gmt":"2024-10-01T09:02:35","slug":"los-precios-de-los-medicamentos-variaron-casi-10-puntos-porcentuales-por-debajo-de-la-inflacion-en-el-primer-trimestre-de-2024","status":"publish","type":"post","link":"https:\/\/cilfa.org.ar\/wp1\/los-precios-de-los-medicamentos-variaron-casi-10-puntos-porcentuales-por-debajo-de-la-inflacion-en-el-primer-trimestre-de-2024\/","title":{"rendered":"Los precios de los medicamentos variaron casi 10 puntos  porcentuales por debajo de la inflaci\u00f3n en el primer trimestre de  2024"},"content":{"rendered":"<div class=\"fusion-fullwidth fullwidth-box fusion-builder-row-1 nonhundred-percent-fullwidth non-hundred-percent-height-scrolling\" style=\"--awb-border-radius-top-left:0px;--awb-border-radius-top-right:0px;--awb-border-radius-bottom-right:0px;--awb-border-radius-bottom-left:0px;--awb-flex-wrap:wrap;\" ><div class=\"fusion-builder-row fusion-row\"><div class=\"fusion-layout-column fusion_builder_column fusion-builder-column-0 fusion_builder_column_1_1 1_1 fusion-one-full fusion-column-first fusion-column-last\" style=\"--awb-padding-top:20px;--awb-bg-size:cover;--awb-margin-bottom:0px;\"><div class=\"fusion-column-wrapper fusion-column-has-shadow fusion-flex-column-wrapper-legacy\"><div class=\"fusion-text fusion-text-1\"><p>Publicados los datos del \u00edndice de precios al consumidor correspondiente a marzo de 2024 por parte del INDEC, se confirma que las variaciones de precios de los medicamentos se mantienen por debajo de la inflaci\u00f3n por tercer mes consecutivo.<br \/>\n<strong><br \/>\nLos precios de los medicamentos en el primer trimestre de 2024<\/strong><\/p>\n<p>Durante enero, cuando la inflaci\u00f3n oficial publicada por el INDEC ascendi\u00f3 a 20,6%, la variaci\u00f3n de los precios de los medicamentos fue de 15,1%, es decir, 5,5 puntos porcentuales por debajo del IPC.<br \/>\nEn febrero la variaci\u00f3n de los precios de los medicamentos fue de 12,2%, tambi\u00e9n por debajo de la inflaci\u00f3n en exactamente 1 punto porcentual, ya que esta ascendi\u00f3 a 13,2% en el mes.<\/p>\n<\/div><div class=\"fusion-text fusion-text-2\"><p><div class=\"fusion-fa-align-left\"><i class=\"fb-icon-element-1 fb-icon-element fontawesome-icon fa fa-cloud-download circle-yes\" style=\"--awb-circlecolor:#4fc3f7;--awb-circlecolor-hover:#4fc3f7;--awb-circlebordercolor:#4fc3f7;--awb-circlebordercolor-hover:#4fc3f7;--awb-circlebordersize:1px;--awb-font-size:14.08px;--awb-width:28.16px;--awb-height:28.16px;--awb-line-height:26.16px;--awb-margin-right:10px;\"><\/i><\/div>\n<a href=\"https:\/\/cilfa.org.ar\/wp1\/wp-content\/uploads\/2024\/10\/2024.04.12_Comunicado-Precios_medicamentos.pdf\" target=\"_blank\" rel=\"noopener noreferrer\">DESCARGAR EL COMUNICADO \/ PDF<\/a><\/p>\n<\/div><div class=\"fusion-clearfix\"><\/div><\/div><\/div><\/div><\/div>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[14],"tags":[],"class_list":["post-1895","post","type-post","status-publish","format-standard","hentry","category-comunicados-de-prensa"],"_links":{"self":[{"href":"https:\/\/cilfa.org.ar\/wp1\/wp-json\/wp\/v2\/posts\/1895","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/cilfa.org.ar\/wp1\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/cilfa.org.ar\/wp1\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/cilfa.org.ar\/wp1\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/cilfa.org.ar\/wp1\/wp-json\/wp\/v2\/comments?post=1895"}],"version-history":[{"count":0,"href":"https:\/\/cilfa.org.ar\/wp1\/wp-json\/wp\/v2\/posts\/1895\/revisions"}],"wp:attachment":[{"href":"https:\/\/cilfa.org.ar\/wp1\/wp-json\/wp\/v2\/media?parent=1895"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/cilfa.org.ar\/wp1\/wp-json\/wp\/v2\/categories?post=1895"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/cilfa.org.ar\/wp1\/wp-json\/wp\/v2\/tags?post=1895"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}